{"id":184,"count":50,"description":"Stripper","link":"https:\/\/www.smutjunkies.com\/updates\/tag\/stripper\/","name":"Stripper","slug":"stripper","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.smutjunkies.com\/updates\/wp-json\/wp\/v2\/tags\/184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.smutjunkies.com\/updates\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.smutjunkies.com\/updates\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.smutjunkies.com\/updates\/wp-json\/wp\/v2\/posts?tags=184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}